{"id":65500,"count":1,"description":"","link":"https:\/\/radioclub.es\/en\/radio-language\/%e6%9c%88%e5%8d%97\/","name":"\u6708\u5357","slug":"%e6%9c%88%e5%8d%97","taxonomy":"radio_language","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/radioclub.es\/en\/wp-json\/wp\/v2\/radio_language\/65500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclub.es\/en\/wp-json\/wp\/v2\/radio_language"}],"about":[{"href":"https:\/\/radioclub.es\/en\/wp-json\/wp\/v2\/taxonomies\/radio_language"}],"wp:post_type":[{"href":"https:\/\/radioclub.es\/en\/wp-json\/wp\/v2\/radio-stations?radio_language=65500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}